{"id":16320,"date":"2020-12-05T09:06:42","date_gmt":"2020-12-05T09:06:42","guid":{"rendered":"https:\/\/wpbingosite.com\/wordpress\/mafoil\/?post_type=product&#038;p=16320"},"modified":"2024-07-24T11:21:29","modified_gmt":"2024-07-24T11:21:29","slug":"kitty-deo-rose","status":"publish","type":"product","link":"https:\/\/sweetkitsecrets.com\/en\/product\/kitty-deo-rose\/","title":{"rendered":"KITTY DEO ROSE"},"content":{"rendered":"<p>Ce d\u00e9odorant est con\u00e7u pour tes parties intimes ! C\u2019est un anti transpirant gr\u00e2ce \u00e0 qui ta Kitty aura une odeur irr\u00e9sistible , et pas qu&#8217;elle: il peut aussi \u00eatre appliqu\u00e9 sur certaines zones intimes comme : en bas des seins , entre les seins, entre les fesses , en dessous des fesses \u2026 toutes les petites zones intimes qui ont tendance \u00e0 transpirer et \u00e0 laisser une mauvaise ordeur , maintenant le probl\u00e8me est r\u00e9gl\u00e9 ! Il est con\u00e7u \u00e0 base d&#8217;ingr\u00e9dients naturels, celui l\u00e0 est \u00e0 la rose .<\/p>","protected":false},"excerpt":{"rendered":"<p>Ce d\u00e9odorant est con\u00e7u pour ta Kitty ! C\u2019est un anti transpirant gr\u00e2ce \u00e0 qui ta Kitty aura une odeur irr\u00e9sistible , il peut aussi \u00eatre appliqu\u00e9 sur certaines zones intimes comme : en bas des seins , entre les seins, entre les fesses , en dessous des fesses \u2026 toutes les petites zones intimes qui ont tendance \u00e0 transpirer et \u00e0 laisser une mauvaise ordeur , maintenant le probl\u00e8me est r\u00e9gl\u00e9 !<\/p>","protected":false},"featured_media":44299,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[141,51],"product_tag":[82],"class_list":{"0":"post-16320","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-deo-intime","7":"product_cat-entretien-kitty-care-routine","8":"product_tag-hot","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/product\/16320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/comments?post=16320"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/media\/44299"}],"wp:attachment":[{"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/media?parent=16320"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/product_brand?post=16320"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/product_cat?post=16320"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sweetkitsecrets.com\/en\/wp-json\/wp\/v2\/product_tag?post=16320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}